{"id":68341,"date":"2024-12-20T07:27:38","date_gmt":"2024-12-20T06:27:38","guid":{"rendered":"https:\/\/www.coatresa.com\/?p=68341"},"modified":"2025-01-06T21:38:12","modified_gmt":"2025-01-06T20:38:12","slug":"projecte-solidari-2024","status":"publish","type":"post","link":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/","title":{"rendered":"Projecte Solidari: El nostre comprom\u00eds anual"},"content":{"rendered":"<div id=\"pl-68341\"  class=\"panel-layout\" ><div id=\"pg-68341-0\"  class=\"panel-grid panel-has-style\" ><div style=\"padding: 0px 0; \" data-overlay=\"true\" data-overlay-color=\"#000000\" class=\"panel-row-style panel-row-style-for-68341-0\" ><div id=\"pgc-68341-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-68341-0-0-0\" class=\"so-panel widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div style=\"text-align: left;\" data-title-color=\"#47425d\" data-headings-color=\"#443f3f\" data-title_alignment=\"center\" class=\"panel-widget-style panel-widget-style-for-68341-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip. Una iniciativa que reflecteix el nostre comprom\u00eds amb la comunitat i el nostre desig de contribuir a causes que marquen la difer\u00e8ncia.<\/p>\n<p>Enguany, la recaptaci\u00f3 aconseguida ha estat donada \u00edntegrament a <a href=\"https:\/\/www2.cruzroja.es\/-\/ayuda-emergencia-dana-2024\"><strong>Creu Roja,<\/strong><\/a> i es destinar\u00e0 a <strong>donar suport a les persones afectades a Val\u00e8ncia<\/strong> pel recent desastre causat per la <strong>DANA<\/strong>, que ha deixat moltes fam\u00edlies en situaci\u00f3 d'emerg\u00e8ncia.<\/p>\n<h2><strong>Recaptaci\u00f3 de fons mitjan\u00e7ant els nostres recobriments antiadherents<\/strong><\/h2>\n<p>Durant tot l'any, el nostre equip recobreix les seves paelles amb els nostres recobriments antiadherents i l'import de cada recobriment es destina \u00edntegrament a aquesta causa. D'aquesta manera, transformem una activitat quotidiana en una oportunitat per ajudar aquells que m\u00e9s ho necessiten.<\/p>\n<h2><strong>Una elecci\u00f3 democr\u00e0tica i significativa<\/strong><\/h2>\n<p>Les associacions benefici\u00e0ries d'aquesta donaci\u00f3 s\u00f3n proposades pel nostre equip. Aquest enfocament participatiu garanteix que tothom se senti part activa d'aquesta iniciativa solid\u00e0ria i que les causes escollides ressonin amb els valors i prioritats del nostre equip.<\/p>\n<p>Ens sentim molt agra\u00efts per l'esfor\u00e7 i la implicaci\u00f3 de tots els que han fet possible aquesta donaci\u00f3. En un any ple de reptes, accions com aquesta ens recorden la import\u00e0ncia de la uni\u00f3 i l'empatia per treballar en un m\u00f3n millor.<\/p>\n<p><a href=\"https:\/\/app.powerbi.com\/view?r=eyJrIjoiOTRkMTJlMjItZDU5OC00ZGQzLThkYjYtNGQ2ZjZkNmQyMGZkIiwidCI6Ijc1OTEwOGY5LWNkYjMtNGIwNC1iOTc2LTNlOWIzZDlhZDBiZSIsImMiOjh9\">Infografia resum de la resposta de Creu Roja davant aquesta emerg\u00e8ncia<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip. Una iniciativa que reflecteix el nostre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":68369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-68341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projecte Solidari: El nostre comprom\u00eds anual - Coatresa<\/title>\n<meta name=\"description\" content=\"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projecte Solidari: El nostre comprom\u00eds anual - Coatresa\" \/>\n<meta property=\"og:description\" content=\"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Coatresa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coatresa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T06:27:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T20:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coatresa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Coatresa\" \/>\n<meta name=\"twitter:site\" content=\"@Coatresa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coatresa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/\"},\"author\":{\"name\":\"Coatresa\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#\\\/schema\\\/person\\\/f05fe5db7715bcdcfc2709225530e86d\"},\"headline\":\"Projecte Solidari: El nostre comprom\u00eds anual\",\"datePublished\":\"2024-12-20T06:27:38+00:00\",\"dateModified\":\"2025-01-06T20:38:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/\"},\"wordCount\":251,\"publisher\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coatresa_Projecte-Solidari-2024-scaled.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/\",\"url\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/\",\"name\":\"Projecte Solidari: El nostre comprom\u00eds anual - Coatresa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coatresa_Projecte-Solidari-2024-scaled.jpg\",\"datePublished\":\"2024-12-20T06:27:38+00:00\",\"dateModified\":\"2025-01-06T20:38:12+00:00\",\"description\":\"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coatresa_Projecte-Solidari-2024-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coatresa_Projecte-Solidari-2024-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/projecte-solidari-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecte Solidari: El nostre comprom\u00eds anual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/\",\"name\":\"Coatresa\",\"description\":\"Aplicaci\u00f3n de recubrimientos antiadherentes y anticorrosivos como el Teflon. Expertos del Powder Coating\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#organization\",\"name\":\"Coatresa\",\"url\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/A_blava_mitja_transp.png\",\"contentUrl\":\"https:\\\/\\\/www.coatresa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/A_blava_mitja_transp.png\",\"width\":340,\"height\":326,\"caption\":\"Coatresa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Coatresa\\\/\",\"https:\\\/\\\/x.com\\\/Coatresa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/coatresa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CoatresaCoatings\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coatresa.com\\\/ca\\\/#\\\/schema\\\/person\\\/f05fe5db7715bcdcfc2709225530e86d\",\"name\":\"Coatresa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"caption\":\"Coatresa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projecte Solidari: El nostre comprom\u00eds anual - Coatresa","description":"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/","og_locale":"ca_ES","og_type":"article","og_title":"Projecte Solidari: El nostre comprom\u00eds anual - Coatresa","og_description":"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.","og_url":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/","og_site_name":"Coatresa","article_publisher":"https:\/\/www.facebook.com\/Coatresa\/","article_published_time":"2024-12-20T06:27:38+00:00","article_modified_time":"2025-01-06T20:38:12+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg","type":"image\/jpeg"}],"author":"Coatresa","twitter_card":"summary_large_image","twitter_creator":"@Coatresa","twitter_site":"@Coatresa","twitter_misc":{"Written by":"Coatresa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#article","isPartOf":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/"},"author":{"name":"Coatresa","@id":"https:\/\/www.coatresa.com\/ca\/#\/schema\/person\/f05fe5db7715bcdcfc2709225530e86d"},"headline":"Projecte Solidari: El nostre comprom\u00eds anual","datePublished":"2024-12-20T06:27:38+00:00","dateModified":"2025-01-06T20:38:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/"},"wordCount":251,"publisher":{"@id":"https:\/\/www.coatresa.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg","articleSection":["Not\u00edcies"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/","url":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/","name":"Projecte Solidari: El nostre comprom\u00eds anual - Coatresa","isPartOf":{"@id":"https:\/\/www.coatresa.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg","datePublished":"2024-12-20T06:27:38+00:00","dateModified":"2025-01-06T20:38:12+00:00","description":"A COATRESA, ens unim anualment per fer una donaci\u00f3 a una associaci\u00f3 escollida pel nostre equip.","breadcrumb":{"@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#primaryimage","url":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg","contentUrl":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2024\/12\/Coatresa_Projecte-Solidari-2024-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.coatresa.com\/ca\/projecte-solidari-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.coatresa.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Projecte Solidari: El nostre comprom\u00eds anual"}]},{"@type":"WebSite","@id":"https:\/\/www.coatresa.com\/ca\/#website","url":"https:\/\/www.coatresa.com\/ca\/","name":"Coatresa","description":"Aplicaci\u00f3n de recubrimientos antiadherentes y anticorrosivos como el Teflon. Expertos del Powder Coating","publisher":{"@id":"https:\/\/www.coatresa.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coatresa.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/www.coatresa.com\/ca\/#organization","name":"Coatresa","url":"https:\/\/www.coatresa.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.coatresa.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2022\/07\/A_blava_mitja_transp.png","contentUrl":"https:\/\/www.coatresa.com\/wp-content\/uploads\/2022\/07\/A_blava_mitja_transp.png","width":340,"height":326,"caption":"Coatresa"},"image":{"@id":"https:\/\/www.coatresa.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coatresa\/","https:\/\/x.com\/Coatresa","https:\/\/www.linkedin.com\/company\/coatresa\/","https:\/\/www.youtube.com\/user\/CoatresaCoatings"]},{"@type":"Person","@id":"https:\/\/www.coatresa.com\/ca\/#\/schema\/person\/f05fe5db7715bcdcfc2709225530e86d","name":"Coatresa","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","caption":"Coatresa"}}]}},"_links":{"self":[{"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/posts\/68341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/comments?post=68341"}],"version-history":[{"count":0,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/posts\/68341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/media\/68369"}],"wp:attachment":[{"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/media?parent=68341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/categories?post=68341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coatresa.com\/ca\/wp-json\/wp\/v2\/tags?post=68341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}